{"id":13581,"date":"2024-04-17T11:33:33","date_gmt":"2024-04-17T03:33:33","guid":{"rendered":"https:\/\/web.ts.com.tw\/ja\/?page_id=13581"},"modified":"2024-06-25T15:07:12","modified_gmt":"2024-06-25T07:07:12","slug":"6600w-surface-mount-tvs","status":"publish","type":"page","link":"https:\/\/web.ts.com.tw\/ja\/resources\/infographic\/6600w-surface-mount-tvs\/","title":{"rendered":"6600W Surface Mount TVS"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13581\" class=\"elementor elementor-13581\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-01d956b e-flex e-con-boxed e-con e-parent\" data-id=\"01d956b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0f17b4 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a0f17b4\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Infographic<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-07aaa50 e-flex e-con-boxed e-con e-parent\" data-id=\"07aaa50\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[],&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a0903d0 jet-breadcrumbs-on-front-yes jet-breadcrumbs-align-left breadcrumb-icon elementor-widget elementor-widget-jet-breadcrumbs\" data-id=\"a0903d0\" data-element_type=\"widget\" data-widget_type=\"jet-breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"elementor-jet-breadcrumbs jet-blocks\">\n\t\t<div class=\"jet-breadcrumbs\">\n\t\t<div class=\"jet-breadcrumbs__content\">\n\t\t<div class=\"jet-breadcrumbs__wrap\"><div class=\"jet-breadcrumbs__item\"><a href=\"https:\/\/web.ts.com.tw\/ja\/\" class=\"jet-breadcrumbs__item-link is-home\" rel=\"home\" title=\"Home\">Home<\/a><\/div>\n\t\t<\/div>\n\t\t<\/div>\n\t\t<\/div><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5934c1 e-flex e-con-boxed e-con e-parent\" data-id=\"e5934c1\" data-element_type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;_id&quot;:&quot;e4c8d12&quot;,&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:null,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}],&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-acc87cf e-flex e-con-boxed e-con e-child\" data-id=\"acc87cf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1ee92bc elementor-widget elementor-widget-image\" data-id=\"1ee92bc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"\/ja\/wp-content\/uploads\/2024\/04\/tsc-taiwan-semiconductor-6600w-tvs.pdf\" target=\"_blank\">\n\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"720\" height=\"405\" src=\"https:\/\/web.ts.com.tw\/ja\/wp-content\/uploads\/2024\/04\/tsc-taiwan-semiconductor-6600w-tvs-720.jpg?ver=1719300915\" class=\"attachment-large size-large wp-image-13565\" alt=\"Key information of 6600W TVS summarized in graphic elements and picture\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c59788 elementor-widget elementor-widget-text-editor\" data-id=\"7c59788\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Click image to view in PDF file mode.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1e9d303 e-flex e-con-boxed e-con e-child\" data-id=\"1e9d303\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;jet_parallax_layout_list&quot;:[],&quot;content_width&quot;:&quot;boxed&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7f33bb6 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"7f33bb6\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/ja\/wp-content\/uploads\/2024\/04\/TSC_6600W_TVS.pdf\" target=\"_blank\" download=\"\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Download<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0b9eb31 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"0b9eb31\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"\/ja\/product-filter\/?category=tvs-18&#038;current_modifying_property=ppk-w-&#038;conditions=N4IgDmDWC0Du0gFygJYGcD6AnAhgOwHMBTDAeywzwFcAbGpAMxxrSIBoRdCikBtANn4AGIW0EiAugF8pQA\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Product Portfolio<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e24e3c6 elementor-widget__width-initial elementor-hidden-mobile uael-share-buttons--view-icon-text uael-stylex-inline elementor-grid-0 elementor-widget elementor-widget-uael-social-share\" data-id=\"e24e3c6\" data-element_type=\"widget\" data-settings=\"{&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;button_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.85,&quot;sizes&quot;:[]},&quot;columns&quot;:&quot;0&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;button_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"uael-social-share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div class=\"uael-style-inline uael-container uael-floating-align-\" data-pin_data_url=\"\" data-share_url_type=\"current_page\" data-share_url=\"\">\r\n\t\t\t<div class=\"elementor-grid uael-floating-align-\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-facebook\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-square uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on facebook<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">Facebook<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-linkedin\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-square uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on linkedin<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">Linkedin<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-email\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-square uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on email<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uael-share-btn__text\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__title\">Email<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-130ca43 uael-share-buttons--view-icon elementor-grid-mobile-0 elementor-share-buttons-mobile--align-center elementor-widget__width-initial elementor-hidden-desktop elementor-hidden-tablet uael-stylex-inline elementor-grid-0 elementor-widget elementor-widget-uael-social-share\" data-id=\"130ca43\" data-element_type=\"widget\" data-settings=\"{&quot;columns_mobile&quot;:&quot;0&quot;,&quot;alignment_mobile&quot;:&quot;center&quot;,&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;button_size&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0.85,&quot;sizes&quot;:[]},&quot;columns&quot;:&quot;0&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:0,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:10,&quot;sizes&quot;:[]},&quot;button_size_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_size_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;button_height_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size_tablet&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;icon_size_mobile&quot;:{&quot;unit&quot;:&quot;em&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"uael-social-share.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\r\n\t\t<div class=\"uael-style-inline uael-container uael-floating-align-\" data-pin_data_url=\"\" data-share_url_type=\"current_page\" data-share_url=\"\">\r\n\t\t\t<div class=\"elementor-grid uael-floating-align-\">\r\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-facebook\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-rounded uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on facebook<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-linkedin\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-rounded uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on linkedin<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\">\r\n\t\t\t\t\t\t\t\t\t\t\t\t<a  class=\"uael-share-btn-email\">\r\n\t\t\t\t\t\t\t<div class=\"uael-share-btn elementor-animation- uaelbtn-shape-rounded uaelbtn--skin-gradient\">\r\n\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"uael-share-btn__icon\">\r\n\t\t\t\t\t\t\t\t\t\t\t<i class=\"fas fa-envelope\" aria-hidden=\"true\"><\/i>\r\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-screen-only\">Share on email<\/span>\r\n\t\t\t\t\t\t\t\t\t\t<\/span>\r\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<\/a>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Infographic Home Click image to view in PDF file mode. Download Product Portfolio Share on facebook Facebook Share on linkedin Linkedin Share on email Email Share on facebook Share on linkedin Share on email<\/p>\n","protected":false},"author":27,"featured_media":0,"parent":13602,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"full-width-container","site-content-style":"unboxed","site-sidebar-style":"unboxed","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"folder":[71],"class_list":["post-13581","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/pages\/13581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/comments?post=13581"}],"version-history":[{"count":75,"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/pages\/13581\/revisions"}],"predecessor-version":[{"id":14295,"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/pages\/13581\/revisions\/14295"}],"up":[{"embeddable":true,"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/pages\/13602"}],"wp:attachment":[{"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/media?parent=13581"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/web.ts.com.tw\/ja\/wp-json\/wp\/v2\/folder?post=13581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}